{"id":7345,"date":"2024-08-20T13:54:33","date_gmt":"2024-08-20T11:54:33","guid":{"rendered":"https:\/\/aaspirits.com\/san-francisco-world-spirits-competition-2024\/"},"modified":"2024-08-20T13:54:34","modified_gmt":"2024-08-20T11:54:34","slug":"san-francisco-world-spirits-competition-2024","status":"publish","type":"page","link":"https:\/\/aaspirits.com\/fr\/san-francisco-world-spirits-competition-2024\/","title":{"rendered":"SAN FRANCISCO WORLD SPIRITS COMPETITION 2024"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.3&Prime; background_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.10.3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb column_structure=\u00a0\u00bb1_2,1_2&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.10.3&Prime; custom_padding=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; text_font=\u00a0\u00bbLibre Franklin||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#b09b62&Prime; header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_font=\u00a0\u00bbLibre Franklin|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_5_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_5_text_color=\u00a0\u00bb#ffcf9a\u00a0\u00bb header_5_font_size=\u00a0\u00bb14px\u00a0\u00bb header_5_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_5_line_height=\u00a0\u00bb1.2em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_padding=\u00a0\u00bb24px|||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h3>SAN FRANCISCO WORLD SPIRITS COMPETITION 2024<\/h3>\n<p>&nbsp;<\/p>\n<h2>GOLD<\/h2>\n<h2>Pour AAGIN Dry Gin<\/h2>\n<h2>et<\/h2>\n<h2>AAVODKA RYE BERLIN<\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; text_font=\u00a0\u00bbLibre Franklin||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#b09b62&Prime; header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_font=\u00a0\u00bbLibre Franklin|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_5_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_5_text_color=\u00a0\u00bb#ffcf9a\u00a0\u00bb header_5_font_size=\u00a0\u00bb14px\u00a0\u00bb header_5_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_5_line_height=\u00a0\u00bb1.2em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_padding=\u00a0\u00bb24px|||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb]<\/p>\n<h3>San Francisco World Spirits Awards<\/h3>\n<p>&nbsp;<\/p>\n<h3>AAGIN Dry Gin &#8211; 2024 &#8211; GOLD &#8211; 91 Points<\/h3>\n<h3>AAVODKA RYE BERLIN &#8211; 2024 &#8211; GOLD &#8211; 90 Points<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#b09b62&Prime; header_2_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_font=\u00a0\u00bbLibre Franklin|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_5_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_5_text_color=\u00a0\u00bb#ffcf9a\u00a0\u00bb header_5_font_size=\u00a0\u00bb14px\u00a0\u00bb header_5_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_5_line_height=\u00a0\u00bb1.2em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_padding=\u00a0\u00bb24px|||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb24px|||||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb24px|||||\u00a0\u00bb]<\/p>\n<h3>San Francisco World Spirits Awards<\/h3>\n<p>&nbsp;<\/p>\n<h3>AAGIN Dry Gin<br \/>2024 &#8211; GOLD &#8211; 91 Points<\/h3>\n<h3>AAVODKA RYE BERLIN<br \/>2024 &#8211; GOLD &#8211; 90 Points<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb1_2&Prime;][et_pb_image src=\u00a0\u00bbhttps:\/\/aaspirits.com\/wp-content\/uploads\/2024\/06\/2024-SFWSC-Gold-Med.-Artwork.png\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb450px|60px|||false|false\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb height=\u00a0\u00bb200px\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px|0px|||false|false\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb height_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb height_tablet=\u00a0\u00bb150px\u00a0\u00bb height_phone=\u00a0\u00bb150px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb25px||-50px||false|false\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb show_bottom_space_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_margin_phone=\u00a0\u00bb25px||-50px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px|0px|||false|false\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.10.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#000000&Prime; background_color_gradient_end=\u00a0\u00bb#2d2d2d\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/aaspirits.com\/wp-content\/uploads\/2021\/08\/AAGIN-bottle_front.png\u00a0\u00bb title_text=\u00a0\u00bbFalstaff_GIN\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/aaspirits.com\/wp-content\/uploads\/2023\/08\/AAVODKA-RYE-BERLIN.png\u00a0\u00bb title_text=\u00a0\u00bbFalstaffUrkundeAAVERMOUTH\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb admin_label=\u00a0\u00bbCTA\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.3&Prime; background_color=\u00a0\u00bb#000000&Prime; background_image=\u00a0\u00bbhttps:\/\/aaspirits.com\/wp-content\/uploads\/2021\/08\/AAGIN-Background-02.jpg\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb min_height=\u00a0\u00bb813.7px\u00a0\u00bb custom_margin=\u00a0\u00bb||66px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb12vw|80px|12vw||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|0px|||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|40px|||false|false\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset6&Prime; box_shadow_vertical=\u00a0\u00bb-412px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb500px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb-270px\u00a0\u00bb box_shadow_color=\u00a0\u00bb#160b00&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb90%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb custom_padding=\u00a0\u00bb40px||40px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb30px||30px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb20px||20px||true|false\u00a0\u00bb module_alignment_tablet=\u00a0\u00bb\u00a0\u00bb module_alignment_phone=\u00a0\u00bbright\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_color_all=\u00a0\u00bbrgba(255,235,214,0.2)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.11&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/aaspirits.com\/wp-content\/uploads\/2021\/08\/AAGIN-flascheglas2-1.png\u00a0\u00bb title_text=\u00a0\u00bbAAGIN-flasche+glas2&Prime; _builder_version=\u00a0\u00bb4.9.11&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.9.11&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.11&Prime; text_text_color=\u00a0\u00bbrgba(255,207,154,0.7)\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb header_2_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_2_font_size=\u00a0\u00bb37px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_font=\u00a0\u00bbLibre Franklin|||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#b09b62&Prime; header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb550px\u00a0\u00bb custom_padding=\u00a0\u00bb104px|||||\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: left;\">ESSAYEZ MAINTENANT<\/h3>\n<h2 style=\"text-align: left;\">PUR PLAISIR \u00c0 LA MAISON<\/h2>\n<p style=\"text-align: left;\">[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE0In19@\u00a0\u00bb button_text=\u00a0\u00bbVISITEZ LA BOUTIQUE\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.11&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#b09b62&Prime; button_border_color=\u00a0\u00bb#b09b62&Prime; button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb custom_padding=\u00a0\u00bb15px|25px|15px|25px|true|true\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_color__hover=\u00a0\u00bb#160b00&Prime; button_text_color__hover_enabled=\u00a0\u00bbon\u00a0\u00bb button_bg_color__hover=\u00a0\u00bb#b09b62&Prime; button_bg_color__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb button_border_color__hover=\u00a0\u00bb#b09b62&Prime; button_border_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_bg_enable_color__hover=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#000000&Prime; background_color_gradient_end=\u00a0\u00bb#000000&Prime; width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1434px\u00a0\u00bb max_width_tablet=\u00a0\u00bb88%\u00a0\u00bb max_width_phone=\u00a0\u00bb95%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb module_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb module_alignment_phone=\u00a0\u00bb\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#b09b62&Prime; text_font_size=\u00a0\u00bb19px\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">SERVICE-HOTLINE<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=\u00a0\u00bb+49 30 814571900&Prime; use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%264%%\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb content_max_width=\u00a0\u00bb1100px\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb icon_font_size=\u00a0\u00bb39px\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb admin_label=\u00a0\u00bbInformationstext\u00a0\u00bb module_id=\u00a0\u00bbtel-nr\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb29px\u00a0\u00bb body_font=\u00a0\u00bbLibre Franklin||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#757575&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb|||41px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blurb][et_pb_blurb icon_placement=\u00a0\u00bbleft\u00a0\u00bb content_max_width=\u00a0\u00bb1100px\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb admin_label=\u00a0\u00bbInformationstext\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb29px\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#757575&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|12px|||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Lun-Jeu. 10.00 bis 12.00 Uhr<br \/>und 13.00 bis 16.00 Uhr<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00a0\u00bb+49 30 814571900&Prime; use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb%%264%%\u00a0\u00bb icon_placement=\u00a0\u00bbleft\u00a0\u00bb content_max_width=\u00a0\u00bb1100px\u00a0\u00bb use_icon_font_size=\u00a0\u00bbon\u00a0\u00bb icon_font_size=\u00a0\u00bb39px\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb admin_label=\u00a0\u00bbInformationstext\u00a0\u00bb module_id=\u00a0\u00bbtel-nr\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb29px\u00a0\u00bb body_font=\u00a0\u00bbLibre Franklin||||||||\u00a0\u00bb body_text_color=\u00a0\u00bb#757575&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\">Lun-Jeu. 10.00 bis 12.00 Uhr<br \/>und 13.00 bis 16.00 Uhr<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.10.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#b09b62&Prime; text_font_size=\u00a0\u00bb19px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">SHOP-SERVICE<\/p>\n<p>[\/et_pb_text][et_pb_menu menu_id=\u00a0\u00bb22&Prime; menu_style=\u00a0\u00bbcentered\u00a0\u00bb active_link_color=\u00a0\u00bb#757575&Prime; module_id=\u00a0\u00bbmenu-footer\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb menu_font=\u00a0\u00bb||||||||\u00a0\u00bb menu_text_color=\u00a0\u00bb#757575&Prime; menu_line_height=\u00a0\u00bb1.1em\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb width=\u00a0\u00bb28%\u00a0\u00bb max_width=\u00a0\u00bb31%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb|||20px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_menu][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; admin_label=\u00a0\u00bbSpalte\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#b09b62&Prime; text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>SOCIALS<\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_social_media_follow_network social_network=\u00a0\u00bbfacebook\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.facebook.com\/aagin.berlin\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#757575&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbinstagram\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.instagram.com\/aaginberlin\/\u00a0\u00bb icon_color=\u00a0\u00bb#ffffff\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#757575&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; admin_label=\u00a0\u00bbSpalte\u00a0\u00bb _builder_version=\u00a0\u00bb4.10.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbOswald||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#b09b62&Prime; text_font_size=\u00a0\u00bb19px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">NEWSLETTER<\/p>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00a0\u00bbAAGIN eine Marke der Weindimensional|ee09b057bd\u00a0\u00bb first_name_field=\u00a0\u00bboff\u00a0\u00bb last_name_field=\u00a0\u00bboff\u00a0\u00bb success_message=\u00a0\u00bbMerci de vous \u00eatre abonn\u00e9!\u00a0\u00bb button_text=\u00a0\u00bbS&#039;inscrire\u00a0\u00bb _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb form_field_background_color=\u00a0\u00bb#000000&Prime; form_field_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb form_field_focus_background_color=\u00a0\u00bb#000000&Prime; form_field_text_align=\u00a0\u00bbcenter\u00a0\u00bb background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#3f3f3f\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_icon=\u00a0\u00bb%%153%%\u00a0\u00bb button_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_icon_placement=\u00a0\u00bbleft\u00a0\u00bb button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii_fields=\u00a0\u00bbon|2px|2px|2px|2px\u00a0\u00bb border_width_all_fields=\u00a0\u00bb3px\u00a0\u00bb border_color_all_fields=\u00a0\u00bb#757575&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_signup][et_pb_code _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] -->#menu-footer {<!-- [et_pb_line_break_holder] -->  text-align: center;<!-- [et_pb_line_break_holder] -->  display: flex;<!-- [et_pb_line_break_holder] -->  justify-content: center;<!-- [et_pb_line_break_holder] -->  align-items: center;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->@media screen and (min-width: 478px) {<!-- [et_pb_line_break_holder] -->  #menu-footer {<!-- [et_pb_line_break_holder] -->    \/* F\u00fcge hier zus\u00e4tzliche Styles f\u00fcr Desktop-Bildschirme hinzu, wenn n\u00f6tig *\/<!-- [et_pb_line_break_holder] -->    text-align: left; \/* Beispiel: Text auf der linken Seite ausrichten *\/<!-- [et_pb_line_break_holder] -->    display: block;   \/* Beispiel: Block-Layout f\u00fcr Desktops *\/<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][et_pb_code _builder_version=\u00a0\u00bb4.11.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] -->#tel-nr {<!-- [et_pb_line_break_holder] -->  text-align: center;<!-- [et_pb_line_break_holder] -->  display: flex;<!-- [et_pb_line_break_holder] -->  justify-content: center;<!-- [et_pb_line_break_holder] -->  align-items: center;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->@media screen and (min-width: 478px) {<!-- [et_pb_line_break_holder] -->  #tel-nr {<!-- [et_pb_line_break_holder] -->    \/* F\u00fcge hier zus\u00e4tzliche Styles f\u00fcr Desktop-Bildschirme hinzu, wenn n\u00f6tig *\/<!-- [et_pb_line_break_holder] -->    text-align: left; \/* Beispiel: Text auf der linken Seite ausrichten *\/<!-- [et_pb_line_break_holder] -->    display: block;   \/* Beispiel: Block-Layout f\u00fcr Desktops *\/<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FRANCISCO WORLD SPIRITS COMPETITION 2024 &nbsp; GOLD Pour AAGIN Dry Gin et AAVODKA RYE BERLIN &nbsp;San Francisco World Spirits Awards &nbsp; AAGIN Dry Gin &#8211; 2024 &#8211; GOLD &#8211; 91 Points AAVODKA RYE BERLIN &#8211; 2024 &#8211; GOLD &#8211; 90 PointsSan Francisco World Spirits Awards &nbsp; AAGIN Dry Gin2024 &#8211; GOLD &#8211; 91 Points [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7345","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/pages\/7345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/comments?post=7345"}],"version-history":[{"count":3,"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/pages\/7345\/revisions"}],"predecessor-version":[{"id":7348,"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/pages\/7345\/revisions\/7348"}],"wp:attachment":[{"href":"https:\/\/aaspirits.com\/fr\/wp-json\/wp\/v2\/media?parent=7345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}